{"id":1094,"date":"2017-01-16T14:50:42","date_gmt":"2017-01-16T13:50:42","guid":{"rendered":"https:\/\/berlin-tagungshotels.com\/de\/?p=1094"},"modified":"2020-05-23T10:45:33","modified_gmt":"2020-05-23T08:45:33","slug":"verweilen-in-der-luzerner-altstadt","status":"publish","type":"post","link":"https:\/\/dresden-meetinghotels.com\/de\/news\/luzerner-altstadt\/","title":{"rendered":"Verweilen in der Luzerner Altstadt"},"content":{"rendered":"<p>Die Luzerner Altstadt ist autofrei, was bei den kurzen Distanzen in der \u00fcberschaubaren Stadt am Vierwaldst\u00e4dtersee kein Problem darstellt.<\/p>\n<h2>Luzerner Altstadt<\/h2>\n<p>Entlang der Reuss mit Blick auf die Kappelbr\u00fccke und den Pilatus, reihen sich Restaurants und Bars aneinander, in welchen man vom Kaffee am Morgen bis zum Feierabend-Bier aus der eigenen Brauerei, alles findet. An kulinarischer Abwechslung wird es Ihnen neben Ihrem kommenden Kongress, Seminar oder Teamevent definitiv nicht fehlen \u2013 wir helfen Ihnen gerne bei der Auswahl.<\/p>\n<p>Kulturell bietet Luzern ganzj\u00e4hrig viele verschiedene Anl\u00e4sse, nicht nur im Kultur- und Kongresszentrum Luzern (KKL). Auch in den Strassen der Altstadt finden nebst der Fasnacht im Winter verschiedene Festivals statt. Die Stadt Luzern bietet viele M\u00f6glichkeiten f\u00fcr ein passendes Rahmenprogramm zu ihrem Anlass.<\/p>","protected":false},"excerpt":{"rendered":"<p>Die Luzerner Altstadt ist autofrei, was bei den kurzen Distanzen in der \u00fcberschaubaren Stadt am Vierwaldst\u00e4dtersee kein Problem darstellt. Luzerner Altstadt Entlang der Reuss mit Blick auf die Kappelbr\u00fccke und den Pilatus, reihen sich Restaurants und Bars aneinander, in welchen man vom Kaffee am Morgen bis zum Feierabend-Bier aus der eigenen Brauerei, alles findet. An [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":1097,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.3 (Yoast SEO v20.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lucerne Old Town - Always a great way to relax | MICE Service Group | Tagungshotels in Dresden &#8211; die Stadt des Barock<\/title>\n<meta name=\"description\" content=\"Enjoy your stay in the Lucerne old town, always worth a trip. Nice old houses and little bars and shops. And the Bachmann coffee shop with the &quot;Tr\u00f6pfli&quot;.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dresden-meetinghotels.com\/en\/news\/lucerne-old-town\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verweilen in der Luzerner Altstadt\" \/>\n<meta property=\"og:description\" content=\"Enjoy your stay in the Lucerne old town, always worth a trip. Nice old houses and little bars and shops. And the Bachmann coffee shop with the &quot;Tr\u00f6pfli&quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dresden-meetinghotels.com\/en\/news\/lucerne-old-town\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-16T13:50:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-23T08:45:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dresden-meetinghotels.com\/wp-content\/uploads\/2017\/01\/48514303_xxl.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1691\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Janin Heukamp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Janin Heukamp\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dresden-meetinghotels.com\/en\/news\/lucerne-old-town\/\",\"url\":\"https:\/\/dresden-meetinghotels.com\/en\/news\/lucerne-old-town\/\",\"name\":\"Lucerne Old Town - Always a great way to relax | MICE Service Group\",\"isPartOf\":{\"@id\":\"https:\/\/berneroberland-seminarhotels.ch\/de\/#website\"},\"datePublished\":\"2017-01-16T13:50:42+00:00\",\"dateModified\":\"2020-05-23T08:45:33+00:00\",\"author\":{\"@id\":\"https:\/\/berneroberland-seminarhotels.ch\/de\/#\/schema\/person\/5bb45c542dcff14e312ec4a4369429c8\"},\"description\":\"Enjoy your stay in the Lucerne old town, always worth a trip. Nice old houses and little bars and shops. And the Bachmann coffee shop with the \\\"Tr\u00f6pfli\\\".\",\"breadcrumb\":{\"@id\":\"https:\/\/dresden-meetinghotels.com\/en\/news\/lucerne-old-town\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dresden-meetinghotels.com\/en\/news\/lucerne-old-town\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dresden-meetinghotels.com\/en\/news\/lucerne-old-town\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/berneroberland-seminarhotels.ch\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\/\/dresden-meetinghotels.com\/de\/news\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Verweilen in der Luzerner Altstadt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/berneroberland-seminarhotels.ch\/de\/#website\",\"url\":\"https:\/\/berneroberland-seminarhotels.ch\/de\/\",\"name\":\"dresden-meetinghotels.com\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/berneroberland-seminarhotels.ch\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/berneroberland-seminarhotels.ch\/de\/#\/schema\/person\/5bb45c542dcff14e312ec4a4369429c8\",\"name\":\"Janin Heukamp\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/berneroberland-seminarhotels.ch\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dresden-meetinghotels.com\/wp-content\/wphb-cache\/gravatar\/8f6\/8f6cee3e8d7a788c16c0a499cc8062b7x96.jpg\",\"contentUrl\":\"https:\/\/dresden-meetinghotels.com\/wp-content\/wphb-cache\/gravatar\/8f6\/8f6cee3e8d7a788c16c0a499cc8062b7x96.jpg\",\"caption\":\"Janin Heukamp\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lucerne Old Town - Always a great way to relax | MICE Service Group | Tagungshotels in Dresden &#8211; die Stadt des Barock","description":"Enjoy your stay in the Lucerne old town, always worth a trip. Nice old houses and little bars and shops. And the Bachmann coffee shop with the \"Tr\u00f6pfli\".","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dresden-meetinghotels.com\/en\/news\/lucerne-old-town\/","og_locale":"de_DE","og_type":"article","og_title":"Verweilen in der Luzerner Altstadt","og_description":"Enjoy your stay in the Lucerne old town, always worth a trip. Nice old houses and little bars and shops. And the Bachmann coffee shop with the \"Tr\u00f6pfli\".","og_url":"https:\/\/dresden-meetinghotels.com\/en\/news\/lucerne-old-town\/","article_published_time":"2017-01-16T13:50:42+00:00","article_modified_time":"2020-05-23T08:45:33+00:00","og_image":[{"width":2560,"height":1691,"url":"https:\/\/dresden-meetinghotels.com\/wp-content\/uploads\/2017\/01\/48514303_xxl.jpg","type":"image\/jpeg"}],"author":"Janin Heukamp","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Janin Heukamp","Gesch\u00e4tzte Lesezeit":"1 Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dresden-meetinghotels.com\/en\/news\/lucerne-old-town\/","url":"https:\/\/dresden-meetinghotels.com\/en\/news\/lucerne-old-town\/","name":"Lucerne Old Town - Always a great way to relax | MICE Service Group","isPartOf":{"@id":"https:\/\/berneroberland-seminarhotels.ch\/de\/#website"},"datePublished":"2017-01-16T13:50:42+00:00","dateModified":"2020-05-23T08:45:33+00:00","author":{"@id":"https:\/\/berneroberland-seminarhotels.ch\/de\/#\/schema\/person\/5bb45c542dcff14e312ec4a4369429c8"},"description":"Enjoy your stay in the Lucerne old town, always worth a trip. Nice old houses and little bars and shops. And the Bachmann coffee shop with the \"Tr\u00f6pfli\".","breadcrumb":{"@id":"https:\/\/dresden-meetinghotels.com\/en\/news\/lucerne-old-town\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dresden-meetinghotels.com\/en\/news\/lucerne-old-town\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dresden-meetinghotels.com\/en\/news\/lucerne-old-town\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/berneroberland-seminarhotels.ch\/de\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/dresden-meetinghotels.com\/de\/news\/"},{"@type":"ListItem","position":3,"name":"Verweilen in der Luzerner Altstadt"}]},{"@type":"WebSite","@id":"https:\/\/berneroberland-seminarhotels.ch\/de\/#website","url":"https:\/\/berneroberland-seminarhotels.ch\/de\/","name":"dresden-meetinghotels.com","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/berneroberland-seminarhotels.ch\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"},{"@type":"Person","@id":"https:\/\/berneroberland-seminarhotels.ch\/de\/#\/schema\/person\/5bb45c542dcff14e312ec4a4369429c8","name":"Janin Heukamp","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/berneroberland-seminarhotels.ch\/de\/#\/schema\/person\/image\/","url":"https:\/\/dresden-meetinghotels.com\/wp-content\/wphb-cache\/gravatar\/8f6\/8f6cee3e8d7a788c16c0a499cc8062b7x96.jpg","contentUrl":"https:\/\/dresden-meetinghotels.com\/wp-content\/wphb-cache\/gravatar\/8f6\/8f6cee3e8d7a788c16c0a499cc8062b7x96.jpg","caption":"Janin Heukamp"}}]}},"_links":{"self":[{"href":"https:\/\/dresden-meetinghotels.com\/de\/wp-json\/wp\/v2\/posts\/1094"}],"collection":[{"href":"https:\/\/dresden-meetinghotels.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dresden-meetinghotels.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dresden-meetinghotels.com\/de\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/dresden-meetinghotels.com\/de\/wp-json\/wp\/v2\/comments?post=1094"}],"version-history":[{"count":0,"href":"https:\/\/dresden-meetinghotels.com\/de\/wp-json\/wp\/v2\/posts\/1094\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dresden-meetinghotels.com\/de\/wp-json\/wp\/v2\/media\/1097"}],"wp:attachment":[{"href":"https:\/\/dresden-meetinghotels.com\/de\/wp-json\/wp\/v2\/media?parent=1094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}